{"id":2445,"date":"2016-03-25T19:09:00","date_gmt":"2016-03-25T18:09:00","guid":{"rendered":"https:\/\/gregforet.com\/?post_type=project&#038;p=2445"},"modified":"2026-05-17T11:15:22","modified_gmt":"2026-05-17T10:15:22","slug":"calimero-season-1","status":"publish","type":"project","link":"https:\/\/gregforet.com\/fr\/project\/calimero-season-1\/","title":{"rendered":"Calimero \u2013 Saison 1"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_flex_section preset--module--divi-section--default\">\n<div class=\"et_pb_row_0 et_pb_row et_flex_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_0 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h1yjkjr--p1i4mg6vjo preset--module--divi-text--slr0za78on preset--module--divi-text--728lw4ct44\"><div class=\"et_pb_text_inner\"><p><a href=\"https:\/\/gregforet.com\/fr\/project_category\/animated\/\">Animation<\/a> | <a href=\"https:\/\/gregforet.com\/fr\/project_category\/pro-credit\/\">Cr\u00e9dit Pro<\/a><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_heading_0 et_pb_heading et_pb_module et_flex_module preset--group--divi-heading--divi-font--hp5h6dj--3z9x6aia7k preset--module--divi-heading--mnf4rel0am preset--module--divi-heading--8tgkq2khqi\"><div class=\"et_pb_heading_container\"><h1 class=\"et_pb_module_header\">Calimero \u2013 Saison 1<\/h1><\/div><\/div>\n\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module et_flex_column_24_24_phone preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--k8a7a1im4y\"><div class=\"et_pb_text_inner\"><p>Les premiers travaux de layout sur les \u00e9pisodes 17 et 18 de la s\u00e9rie d'animation classique pour enfants Angelo Rules. Pose de base et blocage de cam\u00e9ra juste apr\u00e8s mes premiers pas en layout sur Angelo Rules.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_flex_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_video_0 et_pb_video et_pb_module et_flex_module preset--module--divi-video--default\"><div class=\"et_pb_video_box\"><iframe loading=\"lazy\" title=\"Travail de mise en page | Calimero - Saison 1\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/gWXfo-gS7Lg?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_flex_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_2 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h1yjkjr--p1i4mg6vjo preset--module--divi-text--slr0za78on preset--module--divi-text--728lw4ct44\"><div class=\"et_pb_text_inner\"><p>Aper\u00e7u<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_heading_1 et_pb_heading et_pb_module et_flex_module preset--group--divi-heading--divi-font--hp5h6dj--zht45t6892 preset--module--divi-heading--4k5xa9pdrg\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Vue d'ensemble<\/h3><\/div><\/div>\n\n\n<\/div>\n\n<div class=\"et_pb_column_3 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_16_24 et_flex_column_16_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_row_3 et_pb_row et_pb_row_nested et_flex_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_4 et_pb_column et-last-child et_grid_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_group_0 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Client<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><div class=\"border-l-2 border-ember\/40 pl-4\">TeamTO Paris<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_group_1 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>R\u00f4le<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><div class=\"border-l-2 border-ember\/40 pl-4\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">Artist Layout<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_group_2 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Directeur<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><div class=\"border-l-2 border-ember\/40 pl-4\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">\n<p dir=\"auto\">Divers<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_group_3 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Ann\u00e9e<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><div class=\"border-l-2 border-ember\/40 pl-4\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">2012-2013<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_group_4 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_11 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Format<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_12 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><div class=\"border-l-2 border-ember\/40 pl-4\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">\u00c9pisodique \/ T\u00e9l\u00e9vision<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_group_5 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_13 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Port\u00e9e<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_14 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--group--divi-text--divi-font-body--h19rs5u--default preset--group--divi-text--divi-font-body--h1yjkjr--default preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><div class=\"border-l-2 border-ember\/40 pl-4\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">\n<section class=\"relative py-20 lg:py-28\">\n<div class=\"container-tight grid grid-cols-1 lg:grid-cols-3 gap-10 lg:gap-16\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">\n<section class=\"relative py-20 lg:py-28\">\n<div class=\"container-tight grid grid-cols-1 lg:grid-cols-3 gap-10 lg:gap-16\">\n<div class=\"border-l-2 border-ember\/40 pl-4\">\n<p dir=\"auto\">Positions de base layout et planification des prises de vue pour les \u00e9pisodes 17 et 18.<\/p>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les premiers travaux de layout sur les \u00e9pisodes 17 et 18 de la s\u00e9rie d'animation classique pour enfants Angelo Rules. Pose de base et blocage de cam\u00e9ra juste apr\u00e8s mes premiers pas en layout sur Angelo Rules.<\/p>","protected":false},"author":1,"featured_media":299,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"project_category":[127,65],"project_tag":[55,59,160,67,122],"class_list":["post-2445","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-animated","project_category-pro-credit","project_tag-3d","project_tag-cg","project_tag-kids","project_tag-layout","project_tag-series"],"_links":{"self":[{"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/project\/2445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/comments?post=2445"}],"version-history":[{"count":5,"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/project\/2445\/revisions"}],"predecessor-version":[{"id":3056,"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/project\/2445\/revisions\/3056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/media\/299"}],"wp:attachment":[{"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/media?parent=2445"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/project_category?post=2445"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/gregforet.com\/fr\/wp-json\/wp\/v2\/project_tag?post=2445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}